{"id":158,"date":"2020-08-17T02:47:03","date_gmt":"2020-08-17T02:47:03","guid":{"rendered":"https:\/\/hatshepsut-bookstore.com\/?page_id=158"},"modified":"2020-08-17T02:47:03","modified_gmt":"2020-08-17T02:47:03","slug":"faq","status":"publish","type":"page","link":"https:\/\/hatshepsut-bookstore.com\/en\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"<div class=\"wp-block-bwgb-accordion bwgb-accordion mb-8 pb-1 bwgb-6b1a3a2 bwgb-accordion\" id=\"bwgb-6b1a3a2\"><div class=\"wp-block-bwgb-tabs__inner container\"><div class=\"py-4 py-lg-5 py-xl-8\"><h6 class=\"bwgb-accordion__block-title font-weight-medium font-size-7 font-size-xs-25 text-center\">Frequently Asked Questions<\/h6><\/div><div class=\"mx-auto col-lg-8\"><div class=\"faq-accordion\"><div class=\"pb-lg-1\"><h6 class=\"bwgb-accordion__heading font-weight-medium font-size-4 mb-5\">Shopping<\/h6><div id=\"bwgb-6b1a3a2-Accordion\"><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-6b1a3a21-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none\" data-toggle=\"collapse\" data-target=\"#bwgb-6b1a3a21-Collapse\" aria-expanded=\"true\" aria-controls=\"bwgb-6b1a3a21-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">Delivery charges for orders from the Online Shop?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-6b1a3a21-Collapse\" class=\"collapse show\" aria-labelledby=\"bwgb-6b1a3a21-HeadingOne\" data-parent=\"#bwgb-6b1a3a2-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-6b1a3a22-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-6b1a3a22-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-6b1a3a22-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">How long will delivery take?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-6b1a3a22-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-6b1a3a22-HeadingOne\" data-parent=\"#bwgb-6b1a3a2-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-6b1a3a23-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-6b1a3a23-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-6b1a3a23-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">Do I receive an invoice for my order?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-6b1a3a23-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-6b1a3a23-HeadingOne\" data-parent=\"#bwgb-6b1a3a2-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-6b1a3a24-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-6b1a3a24-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-6b1a3a24-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">Tellus ridicdiam eleifend id ullamcorper?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-6b1a3a24-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-6b1a3a24-HeadingOne\" data-parent=\"#bwgb-6b1a3a2-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-bwgb-accordion bwgb-accordion space-bottom-2 space-bottom-lg-3 bwgb-292606a bwgb-accordion\" id=\"bwgb-292606a\"><div class=\"wp-block-bwgb-tabs__inner container\"><div class=\"mx-auto col-lg-8\"><div class=\"faq-accordion\"><div class=\"pb-lg-1\"><h6 class=\"bwgb-accordion__heading font-weight-medium font-size-4 mb-5\">Payment<\/h6><div id=\"bwgb-292606a-Accordion\"><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-292606a1-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none\" data-toggle=\"collapse\" data-target=\"#bwgb-292606a1-Collapse\" aria-expanded=\"true\" aria-controls=\"bwgb-292606a1-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">When the order payment is taken of my bank account?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-292606a1-Collapse\" class=\"collapse show\" aria-labelledby=\"bwgb-292606a1-HeadingOne\" data-parent=\"#bwgb-292606a-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-292606a2-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-292606a2-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-292606a2-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">What is wishlist?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-292606a2-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-292606a2-HeadingOne\" data-parent=\"#bwgb-292606a-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-292606a3-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-292606a3-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-292606a3-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">What should I do if I receive a damaged or wrong product?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-292606a3-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-292606a3-HeadingOne\" data-parent=\"#bwgb-292606a-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-292606a4-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-292606a4-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-292606a4-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">Can I change or cancel my order?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-292606a4-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-292606a4-HeadingOne\" data-parent=\"#bwgb-292606a-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><div class=\"card rounded-0 border-0\"><div class=\"card-collapse card-header p-0 bg-transparent border-bottom-0\" id=\"bwgb-292606a5-HeadingOne\"><button type=\"button\" class=\"collapse-link btn btn-block d-flex align-items-center justify-content-between card-btn py-3 px-3 px-md-4 border rounded-0 shadow-none collapsed\" data-toggle=\"collapse\" data-target=\"#bwgb-292606a5-Collapse\" aria-expanded=\"false\" aria-controls=\"bwgb-292606a5-Collapse\"><span class=\"bwgb-accordion__title mx-md-1\">What is \u201cpackage tracking\u201d in my orders?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"2px\" class=\"minus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M0.000,-0.000 L15.000,-0.000 L15.000,2.000 L0.000,2.000 L0.000,-0.000 Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15px\" height=\"15px\" class=\"plus\" role=\"img\" aria-hidden=\"true\"><path fill-rule=\"evenodd\" fill=\"rgb(22, 22, 25)\" d=\"M15.000,8.000 L9.000,8.000 L9.000,15.000 L7.000,15.000 L7.000,8.000 L0.000,8.000 L0.000,6.000 L7.000,6.000 L7.000,-0.000 L9.000,-0.000 L9.000,6.000 L15.000,6.000 L15.000,8.000 Z\"><\/path><\/svg><\/button><\/div><div id=\"bwgb-292606a5-Collapse\" class=\"collapse\" aria-labelledby=\"bwgb-292606a5-HeadingOne\" data-parent=\"#bwgb-292606a-Accordion\"><div class=\"card-body p-3 p-md-4\"><div class=\"mx-md-1\"><p class=\"bwgb-accordion__description\">A placerat ac vestibulum integer vehicula suspendisse nostra aptent fermentum tempor a magna erat ligula parturient curae sem conubia vestibulum ac inceptos sodales condimentum cursus nunc mi consectetur condimentum.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-158","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/pages\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":0,"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/pages\/158\/revisions"}],"wp:attachment":[{"href":"https:\/\/hatshepsut-bookstore.com\/en\/wp-json\/wp\/v2\/media?parent=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 69fb67aa190636985539e3eb. Config Timestamp: 2026-05-06 16:09:14 UTC, Cached Timestamp: 2026-05-13 19:36:04 UTC -->